{"id":4198,"date":"2018-04-25T09:00:00","date_gmt":"2018-04-25T09:00:00","guid":{"rendered":"https:\/\/www.allenandallen.com\/tractor-trailer-accident-investigations-and-electronic-control-modules\/"},"modified":"2024-04-10T08:46:33","modified_gmt":"2024-04-10T13:46:33","slug":"investigaciones-de-accidentes-de-tractocamiones-y-modulos-de-control-electronico","status":"publish","type":"post","link":"https:\/\/www.allenandallen.com\/es\/blog\/tractor-trailer-accident-investigations-and-electronic-control-modules\/","title":{"rendered":"Investigaciones de accidentes de remolques y m\u00f3dulos de control electr\u00f3nico"},"content":{"rendered":"<p>A\u00a0collision with a semi tractor trailer can result in catastrophic injuries or death. Thorough investigation of a tractor trailer accident is critical\u00a0to your case.\u00a0One tool at our disposal is the technology found in many of today&#8217;s tractor trailers.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4215\" src=\"https:\/\/www.allenandallen.com\/wp-content\/uploads\/2018\/04\/1210.png\" alt=\"\" width=\"1280\" height=\"853\" srcset=\"https:\/\/www.allenandallen.com\/wp-content\/uploads\/2018\/04\/1210.png 1280w, https:\/\/www.allenandallen.com\/wp-content\/uploads\/2018\/04\/1210-300x200.png 300w, https:\/\/www.allenandallen.com\/wp-content\/uploads\/2018\/04\/1210-768x512.png 768w, https:\/\/www.allenandallen.com\/wp-content\/uploads\/2018\/04\/1210-1024x682.png 1024w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/>]<\/p>\n<h2>What is an Electronic Control Module (ECM)?<\/h2>\n<p>An Electronic Control Module (\u201cECM\u201d) is a small computer that collects data in modern passenger vehicles.<a title=\"\" href=\"#ftn1\">[1]<\/a>\u00a0All modern, heavy trucks (i.e., tractor trailers) are equipped with ECMs.<a title=\"\" href=\"#ftn2\">[2]<\/a>\u00a0The basic function of ECMs is to control and monitor the vehicle\u2019s operations.<a title=\"\" href=\"#ftn3\">[3]<\/a>\u00a0This includes recording\u00a0information such as engine performance, fuel efficiency, cruise control, climate control, mechanical problems, airbag systems, and speed-controlled stereo volume.<a title=\"\" href=\"#ftn4\">[4]<\/a>\u00a0ECMs also run diagnostics, detect problems in the vehicle, and turn on dashboard warning indicator lamps.<a title=\"\" href=\"#ftn5\">[5]<\/a>\u00a0If a vehicle is in an accident, certain ECMs record data that can help explain what happened.<a title=\"\" href=\"#ftn6\">[6]<\/a><\/p>\n<h2>What is an Event Data Recorder (EDR)?<\/h2>\n<p>ECMs that are capable of recording crash data are equipped with an Event Data Recorder (\u201cEDR\u201d) function.<a title=\"\" href=\"#ftn7\">[7]<\/a> Usually, the recording function is triggered by an event that is associated with an accident such as hard braking.<a title=\"\" href=\"#ftn8\">[8]<\/a>\u00a0 Engine manufacturers may refer to these triggering events by a variety of names including \u201cHard Brake,\u201d \u201cQuick Stop\u201d or \u201cIncident.\u201d<a title=\"\" href=\"#ftn9\">[9]<\/a>\u00a0Typically, EDRs do not record data over a long period of time;<a title=\"\" href=\"#ftn10\">[10]<\/a>\u00a0however, some EDRs do store certain pre-crash data such as vehicle speed for five to twenty seconds prior to the crash.<a title=\"\" href=\"#ftn11\">[11]<\/a><\/p>\n<p>While this recording function varies between vehicles, many large trucks have some type of EDR function.<a title=\"\" href=\"#ftn12\">[12]<\/a> The type of data that is recorded varies by manufacturer, but typically includes vehicle speed, brake application, percent throttle, engine RPM, and whether cruise control was on or off.<a title=\"\" href=\"#ftn13\">[13]<\/a><\/p>\n<h2>How Event Data Recorders Help Accident Investigations<\/h2>\n<p>The data recorded by ECMs can be very valuable when analyzing an accident.\u00a0Data extraction requires professional engineers that are familiar with the process.<a title=\"\" href=\"#ftn14\">[14]<\/a>\u00a0Each manufacturer requires specific equipment and software to extract the ECM data.<a title=\"\" href=\"#ftn15\">[15]<\/a>\u00a0It is important to review all physical evidence of an accident, as well.\u00a0 In order to provide reliable accident analysis, an accident reconstruction expert or ECM expert must analyze the reliability of any ECM data and consider the data in conjunction with any physical evidence.<a title=\"\" href=\"#ftn16\">[16]<\/a><\/p>\n<hr align=\"left\" size=\"1\" width=\"33%\" \/>\n<p><a title=\"\" name=\"ftn1\"><\/a>[1] ECMs, also referred to as \u201cmodules,\u201d may go by different names depending on their manufacturer, or the system they control.\u00a0 Some examples include: Powertrain Control Modules (PCMs), Body Control Modules (BCMs), Engine Control Modules (ECMs) or Airbag Control Modules (ACMs). \u00a0<a href=\"http:\/\/www.crashforensics.com\/automobiledatarecorders.cfm\" target=\"_blank\" rel=\"noopener\">http:\/\/www.crashforensics.com\/automobiledatarecorders.cfm<\/a><\/p>\n<p><a title=\"\" name=\"ftn2\"><\/a>[2] https:\/\/www.exponent.com\/heavy_truck_electronic_control_module_data\/.<\/p>\n<p><a title=\"\" name=\"ftn3\"><\/a>[3] <em>Id.<\/em><\/p>\n<p><a title=\"\" name=\"ftn4\"><\/a>[4] <a href=\"http:\/\/www.crashforensics.com\/automobiledatarecorders.cfm\" target=\"_blank\" rel=\"noopener\">http:\/\/www.crashforensics.com\/automobiledatarecorders.cfm<\/a>; https:\/\/www.exponent.com\/heavy_truck_electronic_control_module_data\/.<\/p>\n<p><a title=\"\" name=\"ftn5\"><\/a>[5] <a href=\"http:\/\/www.crashforensics.com\/automobiledatarecorders.cfm\" target=\"_blank\" rel=\"noopener\">http:\/\/www.crashforensics.com\/automobiledatarecorders.cfm<\/a>.<\/p>\n<p><a title=\"\" name=\"ftn6\"><\/a>[6] https:\/\/www.exponent.com\/heavy_truck_electronic_control_module_data\/.<\/p>\n<p><a title=\"\" name=\"ftn7\"><\/a>[7] ECMs with Event Data Recorder (EDR) functions are sometimes generically referred to as a \u201cBlack Box\u201d similar to those found on airplanes.\u00a0 An ECM is not a true \u201cBlack Box,\u201d but the description helps explain the function of the device.\u00a0 http:\/\/www.crashforensics.com\/automobiledatarecorders.cfm.<\/p>\n<p><a title=\"\" name=\"ftn8\"><\/a>[8] <em>See<\/em> https:\/\/www.exponent.com\/heavy_truck_electronic_control_module_data\/.<\/p>\n<p><a title=\"\" name=\"ftn9\"><\/a>[9] <em>Id.<\/em><\/p>\n<p><a title=\"\" name=\"ftn10\"><\/a>[10] <a href=\"http:\/\/www.crashforensics.com\/automobiledatarecorders.cfm\" target=\"_blank\" rel=\"noopener\">http:\/\/www.crashforensics.com\/automobiledatarecorders.cfm<\/a>.<\/p>\n<p><a title=\"\" name=\"ftn11\"><\/a>[11] <em>Id.<\/em><\/p>\n<p><a title=\"\" name=\"ftn12\"><\/a>[12] <em>Id.<\/em><\/p>\n<p><a title=\"\" name=\"ftn13\"><\/a>[13] https:\/\/www.exponent.com\/heavy_truck_electronic_control_module_data\/.<\/p>\n<p><a title=\"\" name=\"ftn14\"><\/a>[14] <em>Id. <\/em><\/p>\n<p><a title=\"\" name=\"ftn15\"><\/a>[15] <em>Id.<\/em> \u00a0Some manufacturers also provide specific training and certification.<\/p>\n<p><a title=\"\" name=\"ftn16\"><\/a>[16] <em>Id. <\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un m\u00f3dulo de control electr\u00f3nico (&quot;ECM&quot;) es una peque\u00f1a computadora que recopila datos en los veh\u00edculos de pasajeros modernos. Si un veh\u00edculo sufre un accidente, ciertos ECM pueden registrar datos que pueden ayudar a explicar lo que sucedi\u00f3.<\/p>","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[8],"tags":[19],"class_list":["post-4198","post","type-post","status-publish","format-standard","hentry","category-blog","tag-completed","import-may_new"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Electronic Control Modules, Event Data Recorders and \u201cBlack Boxes\u201d | Virginia Personal Injury Attorneys | Medical Malpractice Lawyers | Richmond, Fredericksburg, Charlottesville, and Petersburg | Allen, Allen, Allen &amp; Allen<\/title>\n<meta name=\"description\" content=\"An Electronic Control Module (\u201cECM\u201d) is a small computer that collects data in modern passenger vehicles. If a vehicle is in an accident, certain ECMs can record data that can help explain what happened.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.allenandallen.com\/es\/blog\/investigaciones-de-accidentes-de-tractocamiones-y-modulos-de-control-electronico\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tractor Trailer Accident Investigations and Electronic Control Modules\" \/>\n<meta property=\"og:description\" content=\"An Electronic Control Module (\u201cECM\u201d) is a small computer that collects data in modern passenger vehicles. If a vehicle is in an accident, certain ECMs can record data that can help explain what happened.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.allenandallen.com\/es\/blog\/investigaciones-de-accidentes-de-tractocamiones-y-modulos-de-control-electronico\/\" \/>\n<meta property=\"og:site_name\" content=\"Allen and Allen\" \/>\n<meta property=\"article:published_time\" content=\"2018-04-25T09:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-10T13:46:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.allenandallen.com\/wp-content\/uploads\/2018\/04\/1210.png\" \/>\n<meta name=\"author\" content=\"allenandallen\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@allenandallen\" \/>\n<meta name=\"twitter:site\" content=\"@allenandallen\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"allenandallen\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"M\u00f3dulos de control electr\u00f3nico, registradores de datos de eventos y &quot;cajas negras&quot; | Abogados de Lesiones Personales en Virginia | Abogados de negligencia m\u00e9dica | Richmond, Fredericksburg, Charlottesville y Petersburg | Allen, Allen, Allen y Allen","description":"Un m\u00f3dulo de control electr\u00f3nico (&quot;ECM&quot;) es una peque\u00f1a computadora que recopila datos en los veh\u00edculos de pasajeros modernos. Si un veh\u00edculo sufre un accidente, ciertos ECM pueden registrar datos que pueden ayudar a explicar lo que sucedi\u00f3.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.allenandallen.com\/es\/blog\/investigaciones-de-accidentes-de-tractocamiones-y-modulos-de-control-electronico\/","og_locale":"es_ES","og_type":"article","og_title":"Tractor Trailer Accident Investigations and Electronic Control Modules","og_description":"An Electronic Control Module (\u201cECM\u201d) is a small computer that collects data in modern passenger vehicles. If a vehicle is in an accident, certain ECMs can record data that can help explain what happened.","og_url":"https:\/\/www.allenandallen.com\/es\/blog\/investigaciones-de-accidentes-de-tractocamiones-y-modulos-de-control-electronico\/","og_site_name":"Allen and Allen","article_published_time":"2018-04-25T09:00:00+00:00","article_modified_time":"2024-04-10T13:46:33+00:00","og_image":[{"url":"https:\/\/www.allenandallen.com\/wp-content\/uploads\/2018\/04\/1210.png","type":"","width":"","height":""}],"author":"allenandallen","twitter_card":"summary_large_image","twitter_creator":"@allenandallen","twitter_site":"@allenandallen","twitter_misc":{"Written by":"allenandallen","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.allenandallen.com\/blog\/tractor-trailer-accident-investigations-and-electronic-control-modules\/#article","isPartOf":{"@id":"https:\/\/www.allenandallen.com\/blog\/tractor-trailer-accident-investigations-and-electronic-control-modules\/"},"author":{"name":"allenandallen","@id":"https:\/\/www.allenandallen.com\/#\/schema\/person\/d290b1112ce0b61ca8fcb226180dc59a"},"headline":"Tractor Trailer Accident Investigations and Electronic Control Modules","datePublished":"2018-04-25T09:00:00+00:00","dateModified":"2024-04-10T13:46:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.allenandallen.com\/blog\/tractor-trailer-accident-investigations-and-electronic-control-modules\/"},"wordCount":559,"image":{"@id":"https:\/\/www.allenandallen.com\/blog\/tractor-trailer-accident-investigations-and-electronic-control-modules\/#primaryimage"},"thumbnailUrl":"https:\/\/www.allenandallen.com\/wp-content\/uploads\/2018\/04\/1210.png","keywords":["Completed"],"articleSection":["Blog"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.allenandallen.com\/blog\/tractor-trailer-accident-investigations-and-electronic-control-modules\/","url":"https:\/\/www.allenandallen.com\/blog\/tractor-trailer-accident-investigations-and-electronic-control-modules\/","name":"M\u00f3dulos de control electr\u00f3nico, registradores de datos de eventos y &quot;cajas negras&quot; | Abogados de Lesiones Personales en Virginia | Abogados de negligencia m\u00e9dica | Richmond, Fredericksburg, Charlottesville y Petersburg | Allen, Allen, Allen y Allen","isPartOf":{"@id":"https:\/\/www.allenandallen.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.allenandallen.com\/blog\/tractor-trailer-accident-investigations-and-electronic-control-modules\/#primaryimage"},"image":{"@id":"https:\/\/www.allenandallen.com\/blog\/tractor-trailer-accident-investigations-and-electronic-control-modules\/#primaryimage"},"thumbnailUrl":"https:\/\/www.allenandallen.com\/wp-content\/uploads\/2018\/04\/1210.png","datePublished":"2018-04-25T09:00:00+00:00","dateModified":"2024-04-10T13:46:33+00:00","author":{"@id":"https:\/\/www.allenandallen.com\/#\/schema\/person\/d290b1112ce0b61ca8fcb226180dc59a"},"description":"Un m\u00f3dulo de control electr\u00f3nico (&quot;ECM&quot;) es una peque\u00f1a computadora que recopila datos en los veh\u00edculos de pasajeros modernos. Si un veh\u00edculo sufre un accidente, ciertos ECM pueden registrar datos que pueden ayudar a explicar lo que sucedi\u00f3.","breadcrumb":{"@id":"https:\/\/www.allenandallen.com\/blog\/tractor-trailer-accident-investigations-and-electronic-control-modules\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.allenandallen.com\/blog\/tractor-trailer-accident-investigations-and-electronic-control-modules\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.allenandallen.com\/blog\/tractor-trailer-accident-investigations-and-electronic-control-modules\/#primaryimage","url":"https:\/\/www.allenandallen.com\/wp-content\/uploads\/2018\/04\/1210.png","contentUrl":"https:\/\/www.allenandallen.com\/wp-content\/uploads\/2018\/04\/1210.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.allenandallen.com\/blog\/tractor-trailer-accident-investigations-and-electronic-control-modules\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Virginia Personal Injury Lawyer","item":"https:\/\/www.allenandallen.com\/"},{"@type":"ListItem","position":2,"name":"Tractor Trailer Accident Investigations and Electronic Control Modules"}]},{"@type":"WebSite","@id":"https:\/\/www.allenandallen.com\/#website","url":"https:\/\/www.allenandallen.com\/","name":"Allen y Allen","description":"Protegiendo a los heridos desde 1910","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.allenandallen.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.allenandallen.com\/#\/schema\/person\/d290b1112ce0b61ca8fcb226180dc59a","name":"Allenandallen","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/c45031d4d7aa59932ede141d7f2f71e26754f52912c1d288fc324750d7fdbe2a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c45031d4d7aa59932ede141d7f2f71e26754f52912c1d288fc324750d7fdbe2a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c45031d4d7aa59932ede141d7f2f71e26754f52912c1d288fc324750d7fdbe2a?s=96&d=mm&r=g","caption":"allenandallen"},"sameAs":["https:\/\/www.allenandallen.com"],"url":"https:\/\/www.allenandallen.com\/es\/author\/allenandallen\/"}]}},"_links":{"self":[{"href":"https:\/\/www.allenandallen.com\/es\/wp-json\/wp\/v2\/posts\/4198","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.allenandallen.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.allenandallen.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.allenandallen.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.allenandallen.com\/es\/wp-json\/wp\/v2\/comments?post=4198"}],"version-history":[{"count":0,"href":"https:\/\/www.allenandallen.com\/es\/wp-json\/wp\/v2\/posts\/4198\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.allenandallen.com\/es\/wp-json\/wp\/v2\/media?parent=4198"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.allenandallen.com\/es\/wp-json\/wp\/v2\/categories?post=4198"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.allenandallen.com\/es\/wp-json\/wp\/v2\/tags?post=4198"}],"curies":[{"name":"Gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}